{"id":109902,"date":"2024-01-20T07:00:49","date_gmt":"2024-01-19T22:00:49","guid":{"rendered":"https:\/\/watv.org\/exhibition-favorite-reviews\/"},"modified":"2025-04-15T16:57:13","modified_gmt":"2025-04-15T07:57:13","slug":"exhibition-favorite-reviews","status":"publish","type":"post","link":"https:\/\/watv.org\/de\/exhibition-favorite-reviews\/","title":{"rendered":"Erfolgreiche Fortsetzung der Ausstellung \u00fcber Mutter, Vater und Medienansichten mit \u00fcberw\u00e4ltigender Resonanz aus allen Gesellschaftsschichten"},"content":{"rendered":"<p>Im Jahr 2023 ist die \u201eWiederer\u00f6ffnung\u201c zu einem globalen Thema geworden. Inmitten der Aufregung, mit dem Ende der COVID-19-Pandemie wieder in den Alltag zur\u00fcckzukehren, wurden die seit etlicher Zeit ausbleibenden verschiedenen Aktivit\u00e4ten in allen Bereichen erneut aufgenommen und verliehen der Gesellschaft frischen Schwung.<\/p>\n<figure class=\"limit\">\n <picture class=\"copyright\"><source media=\"(max-width:450px)\" srcset=\"\/wp-content\/themes\/watv\/images\/posts\/news_240117_01.jpg\"><img decoding=\"async\" src=\"\/wp-content\/themes\/watv\/images\/posts\/news_240117_01.jpg\"\n    srcset=\"\/wp-content\/themes\/watv\/images\/posts\/news_240117_01.jpg,\n            \/wp-content\/themes\/watv\/images\/posts\/news_240117_01@2x.jpg 2x\">\n <\/picture>\n<\/figure>\n<p>Auch die von der Gemeinde Gottes veranstalteten Ausstellungen, die vor der Pandemie mehrere Monate bis mehrere Jahre lang tiefe Emotionen im In- und Ausland vermittelt hatten, \u00f6ffneten ihre T\u00fcren wieder. Im September 2022 wurden die <a href=\"https:\/\/en.churchofgod.wiki\/%E2%80%9COur_Mother%E2%80%9D_Writing_and_Photo_Exhibition\">Ausstellung \u201eUnsere Mutter in Text und Bild\u201c<\/a> (im Folgenden Ausstellung \u201eMutter\u201c) und <a href=\"https:\/\/en.churchofgod.wiki\/%E2%80%98Father%E2%80%99s_True_Heart%E2%80%99_Exhibition\">\u201eDas wahre Herz des Vaters\u201c<\/a> (im Folgenden Ausstellung \u201eVater\u201c) in Changwon bzw. Seoul wiederer\u00f6ffnet. Dank der Unterst\u00fctzung aus verschiedenen Gesellschaftsschichten erweiterten diese Ausstellungen ihre Veranstaltungsorte im Jahr 2023. Auch die Ausstellung \u201eMedienansichten\u201c, die die Entwicklungsgeschichte der Gemeinde Gottes und ihres biblisch fundierten Glaubens vorstellt, spielte eine bedeutende Rolle bei der Kommunikation mit den \u00f6rtlichen Gemeinschaften.<\/p>\n<p>Mit Anbruch des neuen Jahres 2024 haben wir einen genaueren Blick auf die Berichte \u00fcber die im vergangenen Jahr von mehr als 17.000 Personen besuchten Ausstellungen der Gemeinde Gottes und deren in- und externe Bewertungen geworfen.<\/p>\n<h3>Ausstellung \u201eMutter\u201c und Ausstellung \u201eVater\u201c liefern emotionale Auswirkungen \u00fcber Generationen und Kulturen hinaus<\/h3>\n<p>Die durch COVID-19 verursachten gesellschaftlichen und wirtschaftlichen Krisen und der pl\u00f6tzliche \u00dcbergang zu einer Gesellschaft ohne pers\u00f6nlichen Kontakt haben die Menschen dazu veranlasst, \u00fcber die Familie nachzudenken. Die schwierige wirtschaftliche Situation in Familien und die sich wechselseitig versch\u00e4rfenden Generationenkonflikte haben leider in einigen F\u00e4llen zum Zusammenbruch des famili\u00e4ren Gef\u00fcges gef\u00fchrt.<\/p>\n<figure class=\"limit\">\n <picture class=\"copyright\"><source media=\"(max-width:450px)\" srcset=\"\/wp-content\/themes\/watv\/images\/posts\/news_240117_02.jpg\"><img decoding=\"async\" src=\"\/wp-content\/themes\/watv\/images\/posts\/news_240117_02.jpg\"\n    srcset=\"\/wp-content\/themes\/watv\/images\/posts\/news_240117_02.jpg,\n            \/wp-content\/themes\/watv\/images\/posts\/news_240117_02@2x.jpg 2x\">\n <\/picture>\n<\/figure>\n<p>W\u00e4hrend die Bedeutung der Familie zunehmend abnimmt, sto\u00dfen die Ausstellung \u201eMutter\u201c und die Ausstellung \u201eVater\u201c als Vermittler, die die Werte der kindlichen Piet\u00e4t und Familienliebe wiederbeleben, immer mehr auf positive Resonanz. Heuer j\u00e4hrt sich zum 11. Mal die Ausstellung \u201eMutter\u201c, die letztes Jahr eine gro\u00dfe Anzahl von Besuchern in Changwon, Uijeongbu, Daegu, Jeonju und Seoul anzog. Die Folgeausstellung, die Ausstellung \u201eVater\u201c, in Gwangju, Changwon, Seongnam und Wonju lenkte die Aufmerksamkeit der Menschen viel st\u00e4rker auf die W\u00fcrdigung der Wesensart der beiden Eltern. W\u00e4hrend der Pandemie erreichte das Publikum \u00fcber den YouTube-Kanal \u201e<a href=\"https:\/\/watvmedia.org\/de\/channel\/exhibition-on\">Ausstellung ON<\/a>\u201c die Ausstellungen, und kulturbegeisterte B\u00fcrger besuchten beide Ausstellungen; allein im Jahr 2023 \u00fcber 140.000 Besucher. Als sich allenthalben herumsprach, dass es sich da um sehenswerte Ausstellungen handle, begannen sich viele Menschen aus unterschiedlichen Gesellschaftsschichten im Bereich der Bildung, Wissenschaft, Justiz, Presse, Partei, Politik, Regierung, Kultur usw. f\u00fcr sie zu interessieren. \u00dcbrigens wurden die Ausstellungskataloge in mehr als zehn Sprachen erstellt, sodass sie auch f\u00fcr Ausl\u00e4nder grunds\u00e4tzlich ohne fremde Hilfe zug\u00e4nglich waren.<\/p>\n<figure class=\"limit\">\n <picture class=\"copyright\"><source media=\"(max-width:450px)\" srcset=\"\/wp-content\/themes\/watv\/images\/posts\/news_240117_03v2.jpg\"><img decoding=\"async\" src=\"\/wp-content\/themes\/watv\/images\/posts\/news_240117_03v2.jpg\"\n    srcset=\"\/wp-content\/themes\/watv\/images\/posts\/news_240117_03v2.jpg,\n            \/wp-content\/themes\/watv\/images\/posts\/news_240117_03v2@2x.jpg 2x\">\n <\/picture>\n<\/figure>\n<p>Familien, Nachbarn und Bekannte, die sich die Zeit nahmen, die Ausstellungen zu besuchen, waren von den vielf\u00e4ltigen literarischen Werken und Fotos rund um V\u00e4ter und M\u00fctter fasziniert. Bei der sorgf\u00e4ltigen Betrachtung der verschiedenen Artefakte wie der schwei\u00dfgef\u00e4rbten Arbeitskleidung eines Vaters und des handbefleckten N\u00e4hzeugs einer Mutter tauchten die Betrachter in tiefe \u00dcberlegungen ein. Die mehr als 100 Objekte, jedes mit seiner eigenen Geschichte, f\u00fchrten die Zuschauer auf eine nostalgische Reise. Die j\u00fcngere Generation kam dem Leben ihrer Eltern einen Schritt n\u00e4her, w\u00e4hrend die mittleren Generationen auf ihre Vergangenheit zur\u00fcckblickten und daraus gro\u00dfen Trost sch\u00f6pften. Inmitten der unaufhaltsamen Welle der \u201eK-Kultur\u201c waren sogar Ausl\u00e4nder, die die Ausstellungshallen besuchten, von der St\u00e4rke koreanischer V\u00e4ter, die die Entwicklung des modernen und zeitgen\u00f6ssischen Koreas vorangetrieben haben, und von ihrer stillen Liebe, die ihr zugrunde liegt, zu Tr\u00e4nen ger\u00fchrt. Andererseits empfanden sie tiefes Mitgef\u00fchl mit der ewig unver\u00e4nderlichen Liebe der Mutter, des \u201egemeinsamen Nenners der Menschheit\u201c.<\/p>\n<p>Paul Duclos, der peruanische Botschafter in Korea, der die Ausstellung \u201eVater\u201c im <a href=\"https:\/\/en.churchofgod.wiki\/The_New_Jerusalem_Imae_Temple\">Tempel \u201eNeues Jerusalem\u201c in Imae<\/a>  besuchte, dr\u00fcckte seine tiefe Wertsch\u00e4tzung aus und sagte: \u201eEs ist wirklich eine wertvolle Ausstellung. dieser Ausstellung sind nicht auf Korea beschr\u00e4nkt, sondern gelten f\u00fcr alle L\u00e4nder auf der ganzen Welt.\u201c Es gab weiterhin positive Kritiken \u00fcber die soziale Wirkung der Ausstellung. Ein Kommentator aktueller Ereignisse erw\u00e4hnte: \u201eIn einer Zeit, in der die Krise der Familie diskutiert wird, wecken die Ausstellungen das Bewusstsein f\u00fcr den Wert der Familie. Sie zeigt anschaulich, welche Rolle die Kirchen in unserer Gesellschaft spielen sollten.\u201c Ein Bildungsbeamter, der die Ausstellung \u201eMutter\u201c in der Gemeinde Gottes in Hoseong, Jeonju besuchte, dr\u00fcckte seine Bewunderung aus: \u201eDa ich seit \u00fcber 40 Jahren im Bildungsbereich arbeite, habe ich oft dar\u00fcber nachgedacht, wie ich der heranwachsenden zuk\u00fcnftigen Generation helfen kann, kindliche Piet\u00e4t zu verinnerlichen. Und ich glaube, dass die Ausstellung \u201eMutter\u201c einen gro\u00dfen Beitrag dazu leisten wird.\u201c<\/p>\n<p>Im August fand die Ausstellung \u201eMutter\u201c in Huancayo, Zentralperu auf der anderen Seite der Welt statt. Nach den Ausstellungen an Orten wie New York (USA) und Santiago (Chile) war dies die 13. ordnungsgem\u00e4\u00dfe Durchf\u00fchrung der Ausstellung \u201eMutter\u201c im Ausland. Die Ausstellung, die die einfache, aber strahlende Liebe peruanischer M\u00fctter in \u00fcber 140 Werken einf\u00e4ngt, fand bei verschiedenen Gruppen einen \u00fcberw\u00e4ltigenden Anklang, darunter Universit\u00e4tsstudenten, Milit\u00e4rangeh\u00f6rigen und Journalisten, und erhielt herzliche Unterst\u00fctzung von den \u00f6rtlichen Gemeinschaften. Zosimo Cardenas Muje, der Gouverneur von Junin in Peru, sagte: \u201eDiese Ausstellung hat uns erm\u00f6glicht, den Wert der Familie, insbesondere der M\u00fctter, zu erkennen. Ich hoffe, dass diese Art von Aktivit\u00e4t weiterhin wesentliche Werte in unserem Leben wiederherstellen wird.\u201c<\/p>\n<h3>Die Ausstellung \u201eMedienansichten\u201c stellt einen neuen Meilenstein in der Kirchengemeinschaft<\/h3>\n<p>Die Ausstellung \u201eMedienansichten\u201c, die im Februar in Changwon ihre Premiere feierte, hat gro\u00dfe Aufmerksamkeit erregt, und in nur 11 Monaten seit ihrer Er\u00f6ffnung hat die Gesamtzahl der Besucher die Grenze von mehr als 30.000 \u00fcberschritten. Sie erh\u00e4lt Anerkennung f\u00fcr ihre Einblicke in die richtige Richtung, die die Religion im 21. Jahrhundert einschlagen sollte, das durch den deutlichen Niedergang des Christentums in der ganzen Welt gekennzeichnet ist. Die Ausstellung findet auch in Seoul, Suwon und Seongnam statt.<\/p>\n<figure class=\"limit\">\n <picture class=\"copyright\"><source media=\"(max-width:450px)\" srcset=\"\/wp-content\/themes\/watv\/images\/posts\/news_240117_04.jpg\"><img decoding=\"async\" src=\"\/wp-content\/themes\/watv\/images\/posts\/news_240117_04.jpg\"\n    srcset=\"\/wp-content\/themes\/watv\/images\/posts\/news_240117_04.jpg,\n            \/wp-content\/themes\/watv\/images\/posts\/news_240117_04@2x.jpg 2x\">\n <\/picture>\n<\/figure>\n<p>Die Ausstellung erm\u00f6glicht es den Besuchern, den 60-j\u00e4hrigen Weg der Gemeinde Gottes durch die Linse der Medien zu beobachten. Die Ausstellung befasst sich mit der Geschichte des exponentiellen Wachstums der Kirche an \u00fcber 7.500 Standorten in nur wenigen Jahrzehnten rund um den ganzen Globus. Die Ausstellung umfasst verschiedene Facetten, darunter umfangreiche gesellschaftliche Beitr\u00e4ge und erhaltene Auszeichnungen. Der Inhalt ist in vier Hauptthemen gegliedert: \u201eWelt\u201c, \u201eSalz und Licht\u201c, \u201eFamilie und Gl\u00fcck\u201c und \u201eNach der Bibel\u201c. Die kuratierte Ausstellung mit dem Titel \u201eAuf der Suche nach den Wurzeln der Gemeinde Gottes\u201c unterstreicht die festen Wurzeln des Glaubens, die diesem schnellen Wachstum zugrunde liegen. Sie wirft ein Licht auf die Authentizit\u00e4t und Legitimit\u00e4t der vor 2.000 Jahren von Jesus Christus selbst gegr\u00fcndeten Gemeinde Gottes, die die Wahrheit des neuen Bundes bewahrt.<\/p>\n<p>Das vielf\u00e4ltige Publikum, von dem viele \u00fcber verschiedene Medien von den <a href=\"https:\/\/watv.org\/de\/volunteer-intro\/\">ehrenamtlichen Aktivit\u00e4ten<\/a> und <a href=\"https:\/\/watvaward.org\/de\">Auszeichnungen<\/a> der Kirche geh\u00f6rt hatten, \u00e4u\u00dferte nach dem Besuch der Ausstellung ein Gef\u00fchl der Best\u00e4tigung und Hoffnung. Sie sind sich alle einig, das wahre Wesen der Gemeinde Gottes und die Hoffnung in der Religion gesehen und erkannt zu haben. Ein Journalist sagte, dass er die Rolle des echten Glaubens und der Religion neu entdeckt habe. Der Vertreter einer B\u00fcrgerorganisation wies auf die Wirkung der ehrenamtlichen Aktivit\u00e4ten der Kirche hin und schrieb sie der aufrichtigen Praxis auf der Grundlage der Bibel zu. Ein Universit\u00e4tsprofessor tat offen seine Unterst\u00fctzung kund und sch\u00e4tzte das unersch\u00fctterliche Grundprinzip der Gemeinde Gottes, die einen reinen, in der Geschichte und Tradition verwurzelten Glauben hervorhebt, anstatt blind nur den Glauben zu betonen.<\/p>\n<p>Durch die Ausstellung \u201eMedienansichten\u201c st\u00e4rkten die Gemeindemitglieder ihre \u00dcberzeugung und ihren Stolz auf die Wahrheit. Diakon Min Jong-won aus <a href=\"https:\/\/en.churchofgod.wiki\/The_Church_of_God_in_San_Diego,_CA,_USA\">San Diego im US-Bundesstaat Kalifornien<\/a>, der die Ausstellung w\u00e4hrend seines Aufenthalts in Korea besuchte, sagte: \u201eNachdem ich die Ausstellung \u201aMedienansichten\u2018 \u00fcber die Gemeinde Gottes gesehen hatte, war ich stolz auf die Manifestation der Herrlichkeit Gottes darin; zu meinem gro\u00dfen Staunen an mehr Orten, als ich wusste. Die Geistlichen aus \u00dcbersee, die letztes Jahr als Mitglieder der Besuchergruppe Korea besuchten, zeigten ebenfalls Interesse an den Ausstellungen und w\u00fcnschten \u00f6rtliche Veranstaltungen in ihren L\u00e4ndern, was ein wachsendes Interesse an den Ausstellungen sowohl innerhalb als auch au\u00dferhalb der Kirche zeigt. Pastor John Casas aus Washington in <a href=\"https:\/\/en.churchofgod.wiki\/The_Church_of_God_in_Washington,_D.C.,_USA\">D. C., USA<\/a>, sagte: \u201eDie Ausstellung \u201aVater\u2018 hebt nicht nur die Aufopferung des Vaters hervor, sondern bietet auch Einblicke in die w\u00fcnschenswerten Eigenschaften einer Vaterfigur. In den Vereinigten Staaten, wo Probleme mit Bezug auf Familienzerr\u00fcttung durch Trennung oder Scheidung usw. derzeit hochaktuell sind, kann solch eine Ausstellung von gro\u00dfer Bedeutung sein.\u201c Jede solche Ausstellung, die aktiv mit den Nachbarn kommunizierte und Gef\u00fchle der Liebe und R\u00fchrung mit ihnen teilte, wird voraussichtlich auch in diesem Jahr wieder die Besucherinnen und Besucher aus dem ganzen Land und aller Welt begeistern.<\/p>\n","protected":false},"excerpt":{"rendered":"Im Jahr 2023 ist die \u201eWiederer\u00f6ffnung\u201c zu einem globalen Thema geworden. Inmitten der Aufregung, mit dem Ende der COVID-19-Pandemie wieder in den Alltag zur\u00fcckzukehren, wurden die seit etlicher Zeit ausbleibenden verschiedenen Aktivit\u00e4ten in allen Bereichen erneut aufgenommen und verliehen der Gesellschaft frischen Schwung. Auch die von der Gemeinde Gottes veranstalteten Ausstellungen, die vor der Pandemie&#8230;","protected":false},"author":27,"featured_media":106159,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[563,564],"tags":[],"class_list":["post-109902","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","category-global-news"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Erfolgreiche Fortsetzung der Ausstellung \u00fcber Mutter, Vater und Medienansichten mit \u00fcberw\u00e4ltigender Resonanz aus allen Gesellschaftsschichten - GEMEINDE GOTTES DES WELTMISSIONSVEREINS<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/watv.org\/de\/exhibition-favorite-reviews\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Erfolgreiche Fortsetzung der Ausstellung \u00fcber Mutter, Vater und Medienansichten mit \u00fcberw\u00e4ltigender Resonanz aus allen Gesellschaftsschichten - GEMEINDE GOTTES DES WELTMISSIONSVEREINS\" \/>\n<meta property=\"og:description\" content=\"Im Jahr 2023 ist die \u201eWiederer\u00f6ffnung\u201c zu einem globalen Thema geworden. Inmitten der Aufregung, mit dem Ende der COVID-19-Pandemie wieder in den Alltag zur\u00fcckzukehren, wurden die seit etlicher Zeit ausbleibenden verschiedenen Aktivit\u00e4ten in allen Bereichen erneut aufgenommen und verliehen der Gesellschaft frischen Schwung. Auch die von der Gemeinde Gottes veranstalteten Ausstellungen, die vor der Pandemie...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/watv.org\/de\/exhibition-favorite-reviews\/\" \/>\n<meta property=\"og:site_name\" content=\"GEMEINDE GOTTES DES WELTMISSIONSVEREINS\" \/>\n<meta property=\"article:published_time\" content=\"2024-01-19T22:00:49+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-04-15T07:57:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/watv.org\/wp-content\/uploads\/2024\/01\/thum_exhibition_favorite_reviews.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1500\" \/>\n\t<meta property=\"og:image:height\" content=\"998\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"jj\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/watv.org\\\/de\\\/exhibition-favorite-reviews\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/watv.org\\\/de\\\/exhibition-favorite-reviews\\\/\"},\"author\":{\"name\":\"jj\",\"@id\":\"https:\\\/\\\/watv.org\\\/de\\\/#\\\/schema\\\/person\\\/e96d5e3eb42fcbc188ccce755b07dd72\"},\"headline\":\"Erfolgreiche Fortsetzung der Ausstellung \u00fcber Mutter, Vater und Medienansichten mit \u00fcberw\u00e4ltigender Resonanz aus allen Gesellschaftsschichten\",\"datePublished\":\"2024-01-19T22:00:49+00:00\",\"dateModified\":\"2025-04-15T07:57:13+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/watv.org\\\/de\\\/exhibition-favorite-reviews\\\/\"},\"wordCount\":1474,\"publisher\":{\"@id\":\"https:\\\/\\\/watv.org\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/watv.org\\\/de\\\/exhibition-favorite-reviews\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/watv.org\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/thum_exhibition_favorite_reviews.jpg\",\"articleSection\":[\"Welthauptsitz der WMC\",\"Globale Nachrichten\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/watv.org\\\/de\\\/exhibition-favorite-reviews\\\/\",\"url\":\"https:\\\/\\\/watv.org\\\/de\\\/exhibition-favorite-reviews\\\/\",\"name\":\"Erfolgreiche Fortsetzung der Ausstellung \u00fcber Mutter, Vater und Medienansichten mit \u00fcberw\u00e4ltigender Resonanz aus allen Gesellschaftsschichten - GEMEINDE GOTTES DES WELTMISSIONSVEREINS\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/watv.org\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/watv.org\\\/de\\\/exhibition-favorite-reviews\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/watv.org\\\/de\\\/exhibition-favorite-reviews\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/watv.org\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/thum_exhibition_favorite_reviews.jpg\",\"datePublished\":\"2024-01-19T22:00:49+00:00\",\"dateModified\":\"2025-04-15T07:57:13+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/watv.org\\\/de\\\/exhibition-favorite-reviews\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/watv.org\\\/de\\\/exhibition-favorite-reviews\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/watv.org\\\/de\\\/exhibition-favorite-reviews\\\/#primaryimage\",\"url\":\"https:\\\/\\\/watv.org\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/thum_exhibition_favorite_reviews.jpg\",\"contentUrl\":\"https:\\\/\\\/watv.org\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/thum_exhibition_favorite_reviews.jpg\",\"width\":1500,\"height\":998},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/watv.org\\\/de\\\/exhibition-favorite-reviews\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/watv.org\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Erfolgreiche Fortsetzung der Ausstellung \u00fcber Mutter, Vater und Medienansichten mit \u00fcberw\u00e4ltigender Resonanz aus allen Gesellschaftsschichten\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/watv.org\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/watv.org\\\/de\\\/\",\"name\":\"GEMEINDE GOTTES DES WELTMISSIONSVEREINS\",\"description\":\"With Mother\u2019s heartwarming love, we deliver eternal happiness to seven billion people in the world.\",\"publisher\":{\"@id\":\"https:\\\/\\\/watv.org\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/watv.org\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/watv.org\\\/de\\\/#organization\",\"name\":\"World Mission Society Church of God - \ud558\ub098\ub2d8\uc758\uad50\ud68c \uc138\uacc4\ubcf5\uc74c\uc120\uad50\ud611\ud68c\",\"url\":\"https:\\\/\\\/watv.org\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/watv.org\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/watv.org\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/WorldMissionSociety_ChurchofGod_Symbol_Logo.png\",\"contentUrl\":\"https:\\\/\\\/watv.org\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/WorldMissionSociety_ChurchofGod_Symbol_Logo.png\",\"width\":1001,\"height\":1331,\"caption\":\"World Mission Society Church of God - \ud558\ub098\ub2d8\uc758\uad50\ud68c \uc138\uacc4\ubcf5\uc74c\uc120\uad50\ud611\ud68c\"},\"image\":{\"@id\":\"https:\\\/\\\/watv.org\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCioiBk9rS5Dv5j66hUipsuQ\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/watv.org\\\/de\\\/#\\\/schema\\\/person\\\/e96d5e3eb42fcbc188ccce755b07dd72\",\"name\":\"jj\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Erfolgreiche Fortsetzung der Ausstellung \u00fcber Mutter, Vater und Medienansichten mit \u00fcberw\u00e4ltigender Resonanz aus allen Gesellschaftsschichten - GEMEINDE GOTTES DES WELTMISSIONSVEREINS","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/watv.org\/de\/exhibition-favorite-reviews\/","og_locale":"de_DE","og_type":"article","og_title":"Erfolgreiche Fortsetzung der Ausstellung \u00fcber Mutter, Vater und Medienansichten mit \u00fcberw\u00e4ltigender Resonanz aus allen Gesellschaftsschichten - GEMEINDE GOTTES DES WELTMISSIONSVEREINS","og_description":"Im Jahr 2023 ist die \u201eWiederer\u00f6ffnung\u201c zu einem globalen Thema geworden. Inmitten der Aufregung, mit dem Ende der COVID-19-Pandemie wieder in den Alltag zur\u00fcckzukehren, wurden die seit etlicher Zeit ausbleibenden verschiedenen Aktivit\u00e4ten in allen Bereichen erneut aufgenommen und verliehen der Gesellschaft frischen Schwung. Auch die von der Gemeinde Gottes veranstalteten Ausstellungen, die vor der Pandemie...","og_url":"https:\/\/watv.org\/de\/exhibition-favorite-reviews\/","og_site_name":"GEMEINDE GOTTES DES WELTMISSIONSVEREINS","article_published_time":"2024-01-19T22:00:49+00:00","article_modified_time":"2025-04-15T07:57:13+00:00","og_image":[{"width":1500,"height":998,"url":"https:\/\/watv.org\/wp-content\/uploads\/2024\/01\/thum_exhibition_favorite_reviews.jpg","type":"image\/jpeg"}],"author":"jj","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/watv.org\/de\/exhibition-favorite-reviews\/#article","isPartOf":{"@id":"https:\/\/watv.org\/de\/exhibition-favorite-reviews\/"},"author":{"name":"jj","@id":"https:\/\/watv.org\/de\/#\/schema\/person\/e96d5e3eb42fcbc188ccce755b07dd72"},"headline":"Erfolgreiche Fortsetzung der Ausstellung \u00fcber Mutter, Vater und Medienansichten mit \u00fcberw\u00e4ltigender Resonanz aus allen Gesellschaftsschichten","datePublished":"2024-01-19T22:00:49+00:00","dateModified":"2025-04-15T07:57:13+00:00","mainEntityOfPage":{"@id":"https:\/\/watv.org\/de\/exhibition-favorite-reviews\/"},"wordCount":1474,"publisher":{"@id":"https:\/\/watv.org\/de\/#organization"},"image":{"@id":"https:\/\/watv.org\/de\/exhibition-favorite-reviews\/#primaryimage"},"thumbnailUrl":"https:\/\/watv.org\/wp-content\/uploads\/2024\/01\/thum_exhibition_favorite_reviews.jpg","articleSection":["Welthauptsitz der WMC","Globale Nachrichten"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/watv.org\/de\/exhibition-favorite-reviews\/","url":"https:\/\/watv.org\/de\/exhibition-favorite-reviews\/","name":"Erfolgreiche Fortsetzung der Ausstellung \u00fcber Mutter, Vater und Medienansichten mit \u00fcberw\u00e4ltigender Resonanz aus allen Gesellschaftsschichten - GEMEINDE GOTTES DES WELTMISSIONSVEREINS","isPartOf":{"@id":"https:\/\/watv.org\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/watv.org\/de\/exhibition-favorite-reviews\/#primaryimage"},"image":{"@id":"https:\/\/watv.org\/de\/exhibition-favorite-reviews\/#primaryimage"},"thumbnailUrl":"https:\/\/watv.org\/wp-content\/uploads\/2024\/01\/thum_exhibition_favorite_reviews.jpg","datePublished":"2024-01-19T22:00:49+00:00","dateModified":"2025-04-15T07:57:13+00:00","breadcrumb":{"@id":"https:\/\/watv.org\/de\/exhibition-favorite-reviews\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/watv.org\/de\/exhibition-favorite-reviews\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/watv.org\/de\/exhibition-favorite-reviews\/#primaryimage","url":"https:\/\/watv.org\/wp-content\/uploads\/2024\/01\/thum_exhibition_favorite_reviews.jpg","contentUrl":"https:\/\/watv.org\/wp-content\/uploads\/2024\/01\/thum_exhibition_favorite_reviews.jpg","width":1500,"height":998},{"@type":"BreadcrumbList","@id":"https:\/\/watv.org\/de\/exhibition-favorite-reviews\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/watv.org\/de\/"},{"@type":"ListItem","position":2,"name":"Erfolgreiche Fortsetzung der Ausstellung \u00fcber Mutter, Vater und Medienansichten mit \u00fcberw\u00e4ltigender Resonanz aus allen Gesellschaftsschichten"}]},{"@type":"WebSite","@id":"https:\/\/watv.org\/de\/#website","url":"https:\/\/watv.org\/de\/","name":"GEMEINDE GOTTES DES WELTMISSIONSVEREINS","description":"With Mother\u2019s heartwarming love, we deliver eternal happiness to seven billion people in the world.","publisher":{"@id":"https:\/\/watv.org\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/watv.org\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/watv.org\/de\/#organization","name":"World Mission Society Church of God - \ud558\ub098\ub2d8\uc758\uad50\ud68c \uc138\uacc4\ubcf5\uc74c\uc120\uad50\ud611\ud68c","url":"https:\/\/watv.org\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/watv.org\/de\/#\/schema\/logo\/image\/","url":"https:\/\/watv.org\/wp-content\/uploads\/2022\/06\/WorldMissionSociety_ChurchofGod_Symbol_Logo.png","contentUrl":"https:\/\/watv.org\/wp-content\/uploads\/2022\/06\/WorldMissionSociety_ChurchofGod_Symbol_Logo.png","width":1001,"height":1331,"caption":"World Mission Society Church of God - \ud558\ub098\ub2d8\uc758\uad50\ud68c \uc138\uacc4\ubcf5\uc74c\uc120\uad50\ud611\ud68c"},"image":{"@id":"https:\/\/watv.org\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.youtube.com\/channel\/UCioiBk9rS5Dv5j66hUipsuQ"]},{"@type":"Person","@id":"https:\/\/watv.org\/de\/#\/schema\/person\/e96d5e3eb42fcbc188ccce755b07dd72","name":"jj"}]}},"_links":{"self":[{"href":"https:\/\/watv.org\/de\/wp-json\/wp\/v2\/posts\/109902","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/watv.org\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/watv.org\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/watv.org\/de\/wp-json\/wp\/v2\/users\/27"}],"replies":[{"embeddable":true,"href":"https:\/\/watv.org\/de\/wp-json\/wp\/v2\/comments?post=109902"}],"version-history":[{"count":5,"href":"https:\/\/watv.org\/de\/wp-json\/wp\/v2\/posts\/109902\/revisions"}],"predecessor-version":[{"id":133544,"href":"https:\/\/watv.org\/de\/wp-json\/wp\/v2\/posts\/109902\/revisions\/133544"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/watv.org\/de\/wp-json\/wp\/v2\/media\/106159"}],"wp:attachment":[{"href":"https:\/\/watv.org\/de\/wp-json\/wp\/v2\/media?parent=109902"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/watv.org\/de\/wp-json\/wp\/v2\/categories?post=109902"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/watv.org\/de\/wp-json\/wp\/v2\/tags?post=109902"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}