{"id":123946,"date":"2024-07-28T07:00:56","date_gmt":"2024-07-27T22:00:56","guid":{"rendered":"https:\/\/watv.org\/peru-60th-anniversary-celebration\/"},"modified":"2026-02-02T10:26:59","modified_gmt":"2026-02-02T01:26:59","slug":"peru-60th-anniversary-celebration","status":"publish","type":"post","link":"https:\/\/watv.org\/de\/peru-60th-anniversary-celebration\/","title":{"rendered":"Feier zum 60-j\u00e4hrigen Jubil\u00e4um der Gr\u00fcndung der Gemeinde Gottes in Peru"},"content":{"rendered":"<p>Die Monate Juli und August 2024, die durch die <a href=\"https:\/\/watvaward.org\/de\/award\/2573\">Verleihung der Ehrenmedaille des Kongresses der Republik Peru<\/a> und das Tournee-Konzert des Messias-Orchesters gekennzeichnet waren, werden den Gemeindemitgliedern in Peru wahrscheinlich als besonders gesegnete Zeit in Erinnerung bleiben.<\/p>\n<p>Am 28. Juli feierte die Gemeinde Gottes ihr 60-j\u00e4hriges Bestehen im Sportkomplex Villa el Salvador in der Hauptstadt Lima (Peru) und zog \u00fcber 5.000 Mitglieder aus dem ganzen Land an. Die Veranstaltung erinnerte an sechs Jahrzehnte seit der Gemeindegr\u00fcndung durch den <a href=\"https:\/\/ahnsahnghong.com\/de\/\">Christus Ahnsahnghong<\/a>. Sie diente als Anlass, Gottes Gnade f\u00fcr die Ausbreitung des Lichts der <a href=\"https:\/\/watv.org\/de\/truth-intro\/\">Wahrheit<\/a> des <a href=\"https:\/\/en.churchofgod.wiki\/New_Covenant\">neuen Bundes<\/a> von Korea nach Peru zu danken und die Verpflichtung zu bekr\u00e4ftigen, die Evangelisation aller acht Milliarden Menschen zum erfolgreichen Abschluss zu bringen.<\/p>\n<figure class=\"limit\">\n <picture class=\"copyright\"><source media=\"(max-width:450px)\" srcset=\"\/wp-content\/themes\/watv\/images\/posts\/news_240728_01.jpg\"><img decoding=\"async\" src=\"\/wp-content\/themes\/watv\/images\/posts\/news_240728_01.jpg\"\n    srcset=\"\/wp-content\/themes\/watv\/images\/posts\/news_240728_01.jpg,\n            \/wp-content\/themes\/watv\/images\/posts\/news_240728_01@2x.jpg 2x\">\n <\/picture>\n<\/figure>\n<div class=\"divide limit\">\n<figure>\n  <picture class=\"copyright\"><source media=\"(max-width:450px)\" srcset=\"\/wp-content\/themes\/watv\/images\/posts\/news_240728_02.jpg\"><img decoding=\"async\" src=\"\/wp-content\/themes\/watv\/images\/posts\/news_240728_02.jpg\"\n     srcset=\"\/wp-content\/themes\/watv\/images\/posts\/news_240728_02.jpg,\n             \/wp-content\/themes\/watv\/images\/posts\/news_240728_02@2x.jpg 2x\">\n  <\/picture>\n <\/figure>\n<figure>\n  <picture class=\"copyright\"><source media=\"(max-width:450px)\" srcset=\"\/wp-content\/themes\/watv\/images\/posts\/news_240728_03.jpg\"><img decoding=\"async\" src=\"\/wp-content\/themes\/watv\/images\/posts\/news_240728_03.jpg\"\n     srcset=\"\/wp-content\/themes\/watv\/images\/posts\/news_240728_03.jpg,\n             \/wp-content\/themes\/watv\/images\/posts\/news_240728_03@2x.jpg 2x\">\n  <\/picture>\n <\/figure>\n<\/div>\n<p>Im ersten Teil der Feierveranstaltung zum Gr\u00fcndungstag wies Pastor Kim Joo-cheol, Vorsitzender des Hauptsitzes der WMC, beim Festgottesdienst darauf hin, dass die 1964 gegr\u00fcndete <a href=\"https:\/\/en.churchofgod.wiki\/World_Mission_Society_Church_of_God\">Gemeinde Gottes<\/a> jetzt ein betr\u00e4chtliches Wachstum erlebe, in \u00dcbereinstimmung mit der Prophezeiung: \u201eIst dein Anfang auch gering, wird doch dein Ende herrlich sein (LU17: Hiob 8,7).\u201c Er forderte die Anwesenden dazu auf: \u201eIm Vertrauen darauf, dass Gottes <a href=\"https:\/\/en.churchofgod.wiki\/Gospel\">Evangelium<\/a> nicht scheitern wird, lasst uns, erf\u00fcllt mit dem <a href=\"https:\/\/en.churchofgod.wiki\/The_Holy_Spirit\">Heiligen Geist<\/a>, die Evangelisierung Perus, <a href=\"https:\/\/en.churchofgod.wiki\/The_Church_of_God_in_South_America\">S\u00fcdamerika<\/a>s und schlie\u00dflich der <a href=\/de\/world\">ganzen Welt<\/a> vollenden!\u201c<\/p>\n<p>Der zweite Teil der Veranstaltung war eine schwungvolle und erhebende Feier, die den Stolz und den Glauben unter den Mitgliedern f\u00f6rdern sollte. Zu den H\u00f6hepunkten geh\u00f6rten Auftritte eines vereinigten Chors und Kinderchors, ein gemeinsamer F\u00e4chertanz mit peruanischen und koreanischen Mitgliedern, traditionelle Instrumentalmusik Perus und Auff\u00fchrungen des Messias-Orchesters und eines Quartetts. Eine aus \u00f6rtlichen Gl\u00e4ubigen bestehende Cheerleadergruppe lie\u00df die Begeisterung und den Enthusiasmus der Aurah-Supporters der Gemeinde Gottes bei der Universiade 2003 in Daegu wieder aufleben. Die 240 Teilnehmer waren wie ein Herz und eine Seele und dr\u00fcckten durch ihre synchronisierte Darbietung ihre Entschlossenheit zum Ausdruck, das Evangelium mit vereintem Eifer und Willen sowie in aufrichtiger Zusammenarbeit mit allen weltweiten Gl\u00e4ubigen zu verk\u00fcnden.<\/p>\n<figure class=\"limit\">\n <picture class=\"copyright\"><source media=\"(max-width:450px)\" srcset=\"\/wp-content\/themes\/watv\/images\/posts\/news_240728_04.jpg\"><img decoding=\"async\" src=\"\/wp-content\/themes\/watv\/images\/posts\/news_240728_04.jpg\"\n    srcset=\"\/wp-content\/themes\/watv\/images\/posts\/news_240728_04.jpg,\n            \/wp-content\/themes\/watv\/images\/posts\/news_240728_04@2x.jpg 2x\">\n <\/picture>\n<\/figure>\n<div class=\"divide limit\">\n<figure>\n  <picture class=\"copyright\"><source media=\"(max-width:450px)\" srcset=\"\/wp-content\/themes\/watv\/images\/posts\/news_240728_05.jpg\"><img decoding=\"async\" src=\"\/wp-content\/themes\/watv\/images\/posts\/news_240728_05.jpg\"\n     srcset=\"\/wp-content\/themes\/watv\/images\/posts\/news_240728_05.jpg,\n             \/wp-content\/themes\/watv\/images\/posts\/news_240728_05@2x.jpg 2x\">\n  <\/picture>\n <\/figure>\n<figure>\n  <picture class=\"copyright\"><source media=\"(max-width:450px)\" srcset=\"\/wp-content\/themes\/watv\/images\/posts\/news_240728_06.jpg\"><img decoding=\"async\" src=\"\/wp-content\/themes\/watv\/images\/posts\/news_240728_06.jpg\"\n     srcset=\"\/wp-content\/themes\/watv\/images\/posts\/news_240728_06.jpg,\n             \/wp-content\/themes\/watv\/images\/posts\/news_240728_06@2x.jpg 2x\">\n  <\/picture>\n <\/figure>\n<\/div>\n<p>Am 26. Juli fand im <a href=\"https:\/\/www.lima2019.pe\/sedes\/coliseo-dibos\">Eduardo-Dib\u00f3s-Stadion<\/a> in Lima die \u201eEr\u00f6ffnungszeremonie f\u00fcr die Hoffnungsunterst\u00fctzer auf der ganzen Welt\u201c f\u00fcr S\u00fcdamerika statt, an der sich \u00fcber 5.000 Personen beteiligten, darunter s\u00fcdamerikanische Geistliche und Gemeindemitglieder aus ganz Peru. In seiner Er\u00f6ffnungsansprache betonte Hauptpastor Kim Joo-cheol: \u201eIn einer Zeit, in der die Liebe abgek\u00fchlt ist und der Egoismus vorherrscht, leidet das globale Dorf unter dem Klimawandel, Krieg und anderen sozialen Problemen. Es besteht ein dringender Bedarf an Solidarit\u00e4t und grenz\u00fcberschreitendem Handeln. Inspiriert von der Liebe von <a href=\"https:\/\/en.churchofgod.wiki\/God_the_Father_and_God_the_Mother\">Gottvater und Gottmutter<\/a> wird die Gemeinde Gottes die Rolle des \u201aHoffnungstr\u00e4gers\u2018 \u00fcbernehmen, mit dem Ziel, alle acht Milliarden Menschen zu vereinen und Hoffnung \u00fcber Gemeinschaften, Gesellschaften, Nationen und die Welt hinweg zu verbreiten.\u201c<\/p>\n<figure class=\"limit\">\n <picture class=\"copyright\"><source media=\"(max-width:450px)\" srcset=\"\/wp-content\/themes\/watv\/images\/posts\/news_240728_07.jpg\"><img decoding=\"async\" src=\"\/wp-content\/themes\/watv\/images\/posts\/news_240728_07.jpg\"\n    srcset=\"\/wp-content\/themes\/watv\/images\/posts\/news_240728_07.jpg,\n            \/wp-content\/themes\/watv\/images\/posts\/news_240728_07@2x.jpg 2x\">\n <\/picture>\n<\/figure>\n<p>Anschlie\u00dfend gab es einen Bericht \u00fcber die sozialen Aktivit\u00e4ten der Gemeinde Gottes, eine jeweilige Hoffnungserkl\u00e4rung in jedem Bereich und die Verlesung von Resolutionen. Experten aus verschiedenen Bereichen, darunter Professoren, \u00c4rzte, Anw\u00e4lte und ehemalige Geistliche, traten als Vertreter auf die B\u00fchne und verpflichteten sich, Gottes Liebe und Lehren in allen Gesellschaftsschichten als \u201eUnterst\u00fctzer f\u00fcr die Hoffnung\u201c zu praktizieren.<\/p>\n<p>Die Teilnehmer an beiden Veranstaltungen sagten: \u201eWir haben das bemerkenswerte Wachstum des Evangeliums miterlebt, was unsere Hoffnung auf das Himmelreich gest\u00e4rkt hat.\u201c \u201eWir sind stolz, Mitglieder der Gemeinde Gottes zu sein. Dem Vorbild der <a href=\"https:\/\/en.churchofgod.wiki\/Elohim\">Elohim<\/a> folgend werden wir ihre Liebe weit verbreiten\u201c usw. Zu guter Letzt sprachen sie einstimmig ihren sehnlichsten Wunsch aus, durch Evangelisation und gute Taten eine starke, lebendige Botschaft der Hoffnung, G\u00fcte und Liebe \u00fcber S\u00fcdamerika hinaus allen Menschen rund um den ganzen Globus zu \u00fcberbringen.<\/p>\n","protected":false},"excerpt":{"rendered":"Die Monate Juli und August 2024, die durch die Verleihung der Ehrenmedaille des Kongresses der Republik Peru und das Tournee-Konzert des Messias-Orchesters gekennzeichnet waren, werden den Gemeindemitgliedern in Peru wahrscheinlich als besonders gesegnete Zeit in Erinnerung bleiben. Am 28. Juli feierte die Gemeinde Gottes ihr 60-j\u00e4hriges Bestehen im Sportkomplex Villa el Salvador in der Hauptstadt&#8230;","protected":false},"author":28,"featured_media":121117,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"post-type\/post-type-header-full-screen.php","format":"standard","meta":{"footnotes":""},"categories":[563,564],"tags":[],"class_list":["post-123946","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","category-global-news"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Feier zum 60-j\u00e4hrigen Jubil\u00e4um der Gr\u00fcndung der Gemeinde Gottes in Peru - GEMEINDE GOTTES DES WELTMISSIONSVEREINS<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/watv.org\/de\/peru-60th-anniversary-celebration\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Feier zum 60-j\u00e4hrigen Jubil\u00e4um der Gr\u00fcndung der Gemeinde Gottes in Peru - GEMEINDE GOTTES DES WELTMISSIONSVEREINS\" \/>\n<meta property=\"og:description\" content=\"Die Monate Juli und August 2024, die durch die Verleihung der Ehrenmedaille des Kongresses der Republik Peru und das Tournee-Konzert des Messias-Orchesters gekennzeichnet waren, werden den Gemeindemitgliedern in Peru wahrscheinlich als besonders gesegnete Zeit in Erinnerung bleiben. Am 28. Juli feierte die Gemeinde Gottes ihr 60-j\u00e4hriges Bestehen im Sportkomplex Villa el Salvador in der Hauptstadt...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/watv.org\/de\/peru-60th-anniversary-celebration\/\" \/>\n<meta property=\"og:site_name\" content=\"GEMEINDE GOTTES DES WELTMISSIONSVEREINS\" \/>\n<meta property=\"article:published_time\" content=\"2024-07-27T22:00:56+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-02T01:26:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/watv.org\/wp-content\/uploads\/2024\/07\/thum_peru_60th_anniversary_celebration@2x.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"3000\" \/>\n\t<meta property=\"og:image:height\" content=\"1695\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"jm\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/watv.org\\\/de\\\/peru-60th-anniversary-celebration\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/watv.org\\\/de\\\/peru-60th-anniversary-celebration\\\/\"},\"author\":{\"name\":\"jm\",\"@id\":\"https:\\\/\\\/watv.org\\\/de\\\/#\\\/schema\\\/person\\\/be57f76f5750fcbbbfb6c20b6b68cede\"},\"headline\":\"Feier zum 60-j\u00e4hrigen Jubil\u00e4um der Gr\u00fcndung der Gemeinde Gottes in Peru\",\"datePublished\":\"2024-07-27T22:00:56+00:00\",\"dateModified\":\"2026-02-02T01:26:59+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/watv.org\\\/de\\\/peru-60th-anniversary-celebration\\\/\"},\"wordCount\":216,\"publisher\":{\"@id\":\"https:\\\/\\\/watv.org\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/watv.org\\\/de\\\/peru-60th-anniversary-celebration\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/watv.org\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/thum_peru_60th_anniversary_celebration@2x.jpg\",\"articleSection\":[\"Welthauptsitz der WMC\",\"Globale Nachrichten\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/watv.org\\\/de\\\/peru-60th-anniversary-celebration\\\/\",\"url\":\"https:\\\/\\\/watv.org\\\/de\\\/peru-60th-anniversary-celebration\\\/\",\"name\":\"Feier zum 60-j\u00e4hrigen Jubil\u00e4um der Gr\u00fcndung der Gemeinde Gottes in Peru - GEMEINDE GOTTES DES WELTMISSIONSVEREINS\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/watv.org\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/watv.org\\\/de\\\/peru-60th-anniversary-celebration\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/watv.org\\\/de\\\/peru-60th-anniversary-celebration\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/watv.org\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/thum_peru_60th_anniversary_celebration@2x.jpg\",\"datePublished\":\"2024-07-27T22:00:56+00:00\",\"dateModified\":\"2026-02-02T01:26:59+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/watv.org\\\/de\\\/peru-60th-anniversary-celebration\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/watv.org\\\/de\\\/peru-60th-anniversary-celebration\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/watv.org\\\/de\\\/peru-60th-anniversary-celebration\\\/#primaryimage\",\"url\":\"https:\\\/\\\/watv.org\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/thum_peru_60th_anniversary_celebration@2x.jpg\",\"contentUrl\":\"https:\\\/\\\/watv.org\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/thum_peru_60th_anniversary_celebration@2x.jpg\",\"width\":3000,\"height\":1695},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/watv.org\\\/de\\\/peru-60th-anniversary-celebration\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/watv.org\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Feier zum 60-j\u00e4hrigen Jubil\u00e4um der Gr\u00fcndung der Gemeinde Gottes in Peru\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/watv.org\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/watv.org\\\/de\\\/\",\"name\":\"GEMEINDE GOTTES DES WELTMISSIONSVEREINS\",\"description\":\"With Mother\u2019s heartwarming love, we deliver eternal happiness to seven billion people in the world.\",\"publisher\":{\"@id\":\"https:\\\/\\\/watv.org\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/watv.org\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/watv.org\\\/de\\\/#organization\",\"name\":\"World Mission Society Church of God - \ud558\ub098\ub2d8\uc758\uad50\ud68c \uc138\uacc4\ubcf5\uc74c\uc120\uad50\ud611\ud68c\",\"url\":\"https:\\\/\\\/watv.org\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/watv.org\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/watv.org\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/WorldMissionSociety_ChurchofGod_Symbol_Logo.png\",\"contentUrl\":\"https:\\\/\\\/watv.org\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/WorldMissionSociety_ChurchofGod_Symbol_Logo.png\",\"width\":1001,\"height\":1331,\"caption\":\"World Mission Society Church of God - \ud558\ub098\ub2d8\uc758\uad50\ud68c \uc138\uacc4\ubcf5\uc74c\uc120\uad50\ud611\ud68c\"},\"image\":{\"@id\":\"https:\\\/\\\/watv.org\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCioiBk9rS5Dv5j66hUipsuQ\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/watv.org\\\/de\\\/#\\\/schema\\\/person\\\/be57f76f5750fcbbbfb6c20b6b68cede\",\"name\":\"jm\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Feier zum 60-j\u00e4hrigen Jubil\u00e4um der Gr\u00fcndung der Gemeinde Gottes in Peru - GEMEINDE GOTTES DES WELTMISSIONSVEREINS","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/watv.org\/de\/peru-60th-anniversary-celebration\/","og_locale":"de_DE","og_type":"article","og_title":"Feier zum 60-j\u00e4hrigen Jubil\u00e4um der Gr\u00fcndung der Gemeinde Gottes in Peru - GEMEINDE GOTTES DES WELTMISSIONSVEREINS","og_description":"Die Monate Juli und August 2024, die durch die Verleihung der Ehrenmedaille des Kongresses der Republik Peru und das Tournee-Konzert des Messias-Orchesters gekennzeichnet waren, werden den Gemeindemitgliedern in Peru wahrscheinlich als besonders gesegnete Zeit in Erinnerung bleiben. Am 28. Juli feierte die Gemeinde Gottes ihr 60-j\u00e4hriges Bestehen im Sportkomplex Villa el Salvador in der Hauptstadt...","og_url":"https:\/\/watv.org\/de\/peru-60th-anniversary-celebration\/","og_site_name":"GEMEINDE GOTTES DES WELTMISSIONSVEREINS","article_published_time":"2024-07-27T22:00:56+00:00","article_modified_time":"2026-02-02T01:26:59+00:00","og_image":[{"width":3000,"height":1695,"url":"https:\/\/watv.org\/wp-content\/uploads\/2024\/07\/thum_peru_60th_anniversary_celebration@2x.jpg","type":"image\/jpeg"}],"author":"jm","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/watv.org\/de\/peru-60th-anniversary-celebration\/#article","isPartOf":{"@id":"https:\/\/watv.org\/de\/peru-60th-anniversary-celebration\/"},"author":{"name":"jm","@id":"https:\/\/watv.org\/de\/#\/schema\/person\/be57f76f5750fcbbbfb6c20b6b68cede"},"headline":"Feier zum 60-j\u00e4hrigen Jubil\u00e4um der Gr\u00fcndung der Gemeinde Gottes in Peru","datePublished":"2024-07-27T22:00:56+00:00","dateModified":"2026-02-02T01:26:59+00:00","mainEntityOfPage":{"@id":"https:\/\/watv.org\/de\/peru-60th-anniversary-celebration\/"},"wordCount":216,"publisher":{"@id":"https:\/\/watv.org\/de\/#organization"},"image":{"@id":"https:\/\/watv.org\/de\/peru-60th-anniversary-celebration\/#primaryimage"},"thumbnailUrl":"https:\/\/watv.org\/wp-content\/uploads\/2024\/07\/thum_peru_60th_anniversary_celebration@2x.jpg","articleSection":["Welthauptsitz der WMC","Globale Nachrichten"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/watv.org\/de\/peru-60th-anniversary-celebration\/","url":"https:\/\/watv.org\/de\/peru-60th-anniversary-celebration\/","name":"Feier zum 60-j\u00e4hrigen Jubil\u00e4um der Gr\u00fcndung der Gemeinde Gottes in Peru - GEMEINDE GOTTES DES WELTMISSIONSVEREINS","isPartOf":{"@id":"https:\/\/watv.org\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/watv.org\/de\/peru-60th-anniversary-celebration\/#primaryimage"},"image":{"@id":"https:\/\/watv.org\/de\/peru-60th-anniversary-celebration\/#primaryimage"},"thumbnailUrl":"https:\/\/watv.org\/wp-content\/uploads\/2024\/07\/thum_peru_60th_anniversary_celebration@2x.jpg","datePublished":"2024-07-27T22:00:56+00:00","dateModified":"2026-02-02T01:26:59+00:00","breadcrumb":{"@id":"https:\/\/watv.org\/de\/peru-60th-anniversary-celebration\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/watv.org\/de\/peru-60th-anniversary-celebration\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/watv.org\/de\/peru-60th-anniversary-celebration\/#primaryimage","url":"https:\/\/watv.org\/wp-content\/uploads\/2024\/07\/thum_peru_60th_anniversary_celebration@2x.jpg","contentUrl":"https:\/\/watv.org\/wp-content\/uploads\/2024\/07\/thum_peru_60th_anniversary_celebration@2x.jpg","width":3000,"height":1695},{"@type":"BreadcrumbList","@id":"https:\/\/watv.org\/de\/peru-60th-anniversary-celebration\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/watv.org\/de\/"},{"@type":"ListItem","position":2,"name":"Feier zum 60-j\u00e4hrigen Jubil\u00e4um der Gr\u00fcndung der Gemeinde Gottes in Peru"}]},{"@type":"WebSite","@id":"https:\/\/watv.org\/de\/#website","url":"https:\/\/watv.org\/de\/","name":"GEMEINDE GOTTES DES WELTMISSIONSVEREINS","description":"With Mother\u2019s heartwarming love, we deliver eternal happiness to seven billion people in the world.","publisher":{"@id":"https:\/\/watv.org\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/watv.org\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/watv.org\/de\/#organization","name":"World Mission Society Church of God - \ud558\ub098\ub2d8\uc758\uad50\ud68c \uc138\uacc4\ubcf5\uc74c\uc120\uad50\ud611\ud68c","url":"https:\/\/watv.org\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/watv.org\/de\/#\/schema\/logo\/image\/","url":"https:\/\/watv.org\/wp-content\/uploads\/2022\/06\/WorldMissionSociety_ChurchofGod_Symbol_Logo.png","contentUrl":"https:\/\/watv.org\/wp-content\/uploads\/2022\/06\/WorldMissionSociety_ChurchofGod_Symbol_Logo.png","width":1001,"height":1331,"caption":"World Mission Society Church of God - \ud558\ub098\ub2d8\uc758\uad50\ud68c \uc138\uacc4\ubcf5\uc74c\uc120\uad50\ud611\ud68c"},"image":{"@id":"https:\/\/watv.org\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.youtube.com\/channel\/UCioiBk9rS5Dv5j66hUipsuQ"]},{"@type":"Person","@id":"https:\/\/watv.org\/de\/#\/schema\/person\/be57f76f5750fcbbbfb6c20b6b68cede","name":"jm"}]}},"_links":{"self":[{"href":"https:\/\/watv.org\/de\/wp-json\/wp\/v2\/posts\/123946","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/watv.org\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/watv.org\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/watv.org\/de\/wp-json\/wp\/v2\/users\/28"}],"replies":[{"embeddable":true,"href":"https:\/\/watv.org\/de\/wp-json\/wp\/v2\/comments?post=123946"}],"version-history":[{"count":4,"href":"https:\/\/watv.org\/de\/wp-json\/wp\/v2\/posts\/123946\/revisions"}],"predecessor-version":[{"id":162601,"href":"https:\/\/watv.org\/de\/wp-json\/wp\/v2\/posts\/123946\/revisions\/162601"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/watv.org\/de\/wp-json\/wp\/v2\/media\/121117"}],"wp:attachment":[{"href":"https:\/\/watv.org\/de\/wp-json\/wp\/v2\/media?parent=123946"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/watv.org\/de\/wp-json\/wp\/v2\/categories?post=123946"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/watv.org\/de\/wp-json\/wp\/v2\/tags?post=123946"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}