{"id":98757,"date":"2023-07-04T07:00:07","date_gmt":"2023-07-03T22:00:07","guid":{"rendered":"https:\/\/watv.org\/asezwao-peru-forum-230704\/"},"modified":"2024-01-30T16:19:43","modified_gmt":"2024-01-30T07:19:43","slug":"asezwao-peru-forum-230704","status":"publish","type":"post","link":"https:\/\/watv.org\/de\/asezwao-peru-forum-230704\/","title":{"rendered":"ASEZ-Forum mit dem Minister f\u00fcr Entwicklung und soziale Eingliederung von Peru"},"content":{"rendered":"<p>Die Gemeinde Gottes, die sich f\u00fcr das Gl\u00fcck der Menschen und eine nachhaltige Umwelt einsetzt, und die peruanische Regierung, die eine nachhaltige Entwicklung der Gesellschaft und des Landes anstrebt, arbeiten solidarisch zusammen. Der peruanische Minister f\u00fcr Entwicklung und soziale Eingliederung, Julio Demartini, besuchte Korea, um am globalen Ministertreffen der Unterst\u00fctzungsl\u00e4nder zur Bewegung \u201eNeues Dorf\u201c 2023 teilzunehmen, das gemeinsam vom koreanischen <a href=\"https:\/\/www.mois.go.kr\/eng\/a01\/engMain.do\">Ministerium f\u00fcr Inneres und Sicherheit<\/a> und der Stadt Busan ausgerichtet wurde. Am 4. Juli besuchte er trotz seines vollen Terminkalenders den Tempel \u201eNeues Jerusalem\u201c in Pangyo, Korea. Zuvor, am 17. Mai, hatte die peruanische Umweltministerin Albina Ruiz, die ebenfalls zu einem Arbeitsbesuch in Korea weilte, an einem <a href=\"\/de\/asez-wao-peru-ministry-of-environment\/\">Treffen mit der ASEZ WAO, der Freiwilligengruppe junger erwachsener Arbeitnehmer der Gemeinde Gottes<\/a>, teilgenommen. Im Juni unternahm das Messias-Orchester der Gemeinde Gottes seine erste <a href=\"\/de\/peru-messiah-orchestra-230609\">Konzerttournee<\/a> durch Peru.<\/p>\n<div class=\"my-gallery divide limit\">\n<figure>\n  <a href=\"\/wp-content\/themes\/watv\/images\/posts\/news_230704_01@2x.jpg\" data-size=\"1400x924\" \n   data-med=\"\/wp-content\/themes\/watv\/images\/posts\/news_230704_01.jpg\" data-med-size=\"960x640\">\n   <img decoding=\"async\" src=\"\/wp-content\/themes\/watv\/images\/posts\/news_230704_01.jpg\" itemprop=\"thumbnail\" alt=\"Image description\" \/>\n  <\/a>\n <\/figure>\n<figure>\n  <a href=\"\/wp-content\/themes\/watv\/images\/posts\/news_230704_02@2x.jpg\" data-size=\"1400x924\" \n   data-med=\"\/wp-content\/themes\/watv\/images\/posts\/news_230704_02.jpg\" data-med-size=\"960x640\">\n   <img decoding=\"async\" src=\"\/wp-content\/themes\/watv\/images\/posts\/news_230704_02.jpg\" itemprop=\"thumbnail\" alt=\"Image description\" \/>\n  <\/a>\n <\/figure>\n<figure>\n  <a href=\"\/wp-content\/themes\/watv\/images\/posts\/news_230704_03@2x.jpg\" data-size=\"1400x924\" \n   data-med=\"\/wp-content\/themes\/watv\/images\/posts\/news_230704_03.jpg\" data-med-size=\"960x640\">\n   <img decoding=\"async\" src=\"\/wp-content\/themes\/watv\/images\/posts\/news_230704_03.jpg\" itemprop=\"thumbnail\" alt=\"Image description\" \/>\n  <\/a>\n <\/figure>\n<figure>\n  <a href=\"\/wp-content\/themes\/watv\/images\/posts\/news_230704_04@2x.jpg\" data-size=\"1400x924\" \n   data-med=\"\/wp-content\/themes\/watv\/images\/posts\/news_230704_04.jpg\" data-med-size=\"960x640\">\n   <img decoding=\"async\" src=\"\/wp-content\/themes\/watv\/images\/posts\/news_230704_04.jpg\" itemprop=\"thumbnail\" alt=\"Image description\" \/>\n  <\/a>\n <\/figure>\n<\/div>\n<p>Minister Demartini traf im Tempel in Pangyo ein, wo er von Hauptpastor Kim Joo-cheol und <a href=\"https:\/\/asez.org\/\">ASEZ<\/a>-Mitgliedern begr\u00fc\u00dft wurde, und nahm am ASEZ-Forum teil. Auf dem Forum, bei dem mehr als 500 ASEZ-Mitglieder aus 40 L\u00e4ndern zugegen waren, betonte Minister Demartini wiederholt, dass alle Mitglieder der Gesellschaft solidarisch f\u00fcr das Wohlergehen der Menschheit arbeiten sollten, und sagte: \u201eAlle Menschen im globalen Dorf sind eine gro\u00dfe Familie, und wir sind Br\u00fcder und Schwestern.\u201c Am Beispiel der anstehenden Probleme in Peru nannte er soziale Ungleichheit und Armut als gemeinsame Probleme der Menschheit und erl\u00e4uterte <a href=\"https:\/\/www.gob.pe\/cunamas\">CUNA MAS<\/a>, das F\u00f6rderprogramm der peruanischen Regierung f\u00fcr die Entwicklung von Kindern unter 36 Monaten in benachteiligten Familien. Er freute sich auch auf die Zusammenarbeit bei den k\u00fcnftigen Aktivit\u00e4ten der ASEZ und unterstrich: \u201eDie Zusammenarbeit zwischen der Regierung und privaten Organisationen ist wichtig, wobei die Beteiligung junger Menschen von wesentlicher Bedeutung ist. Ich hoffe, dass alle, die einen guten Einfluss haben, sich uns anschlie\u00dfen werden, um die Erde zu retten und der Menschheit zu helfen&#8220;.<\/p>\n<figure>\n <picture class=\"copyright\"><source media=\"(max-width:450px)\" srcset=\"\/wp-content\/themes\/watv\/images\/posts\/news_230704_05.jpg\"><img decoding=\"async\" src=\"\/wp-content\/themes\/watv\/images\/posts\/news_230704_05.jpg\"\n    srcset=\"\/wp-content\/themes\/watv\/images\/posts\/news_230704_05.jpg,\n            \/wp-content\/themes\/watv\/images\/posts\/news_230704_05@2x.jpg 2x\">\n <\/picture>\n<\/figure>\n<p>Die ASEZ-Mitglieder applaudierten Minister Demartini f\u00fcr seine Ratschl\u00e4ge, die auf seinem umfassenden Wissen und seiner Erfahrung im \u00f6ffentlichen Dienst beruhen. Bernardo Naranjo, Doktorand an der technischen Universit\u00e4t M\u00fcnchen in Deutschland, sagte: \u201eDer Vortrag vom Minister Demartini war sehr hilfreich, weil die ASEZ nach der COVID-19-Pandemie ihre Aktivit\u00e4ten wieder aufnehmen wird. Ich werde mein Bestes tun, um die Schwierigkeiten der deutschen Gesellschaft zu finden und zu l\u00f6sen.\u201c Jeong Geon-ho, Studentin an der Nationaluniversit\u00e4t Seoul in Korea, \u00e4u\u00dferte sich dazu: \u201eHeutzutage ist es schwierig, sich auch in den Ferien vollst\u00e4ndig zu entspannen, weil die Menschen st\u00e4ndig damit besch\u00e4ftigt sind, ihren Arbeitsplatz zu finden oder auszuw\u00e4hlen. W\u00e4hrend ich mir den heutigen Vortrag anh\u00f6rte, wurde mir klar, dass es nicht nur f\u00fcr mich selbst, sondern auch f\u00fcr uns als Mitglieder der globalen Familie eine Menge zu tun gibt.\u201c<\/p>\n<div class=\"my-gallery divide limit\">\n<figure>\n  <a href=\"\/wp-content\/themes\/watv\/images\/posts\/news_230704_06@2x.jpg\" data-size=\"1400x924\" \n   data-med=\"\/wp-content\/themes\/watv\/images\/posts\/news_230704_06.jpg\" data-med-size=\"960x640\">\n   <img decoding=\"async\" src=\"\/wp-content\/themes\/watv\/images\/posts\/news_230704_06.jpg\" itemprop=\"thumbnail\" alt=\"Image description\" \/>\n  <\/a>\n <\/figure>\n<figure>\n  <a href=\"\/wp-content\/themes\/watv\/images\/posts\/news_230704_07@2x.jpg\" data-size=\"1400x924\" \n   data-med=\"\/wp-content\/themes\/watv\/images\/posts\/news_230704_07.jpg\" data-med-size=\"960x640\">\n   <img decoding=\"async\" src=\"\/wp-content\/themes\/watv\/images\/posts\/news_230704_07.jpg\" itemprop=\"thumbnail\" alt=\"Image description\" \/>\n  <\/a>\n <\/figure>\n<figure>\n  <a href=\"\/wp-content\/themes\/watv\/images\/posts\/news_230704_08@2x.jpg\" data-size=\"1400x924\" \n   data-med=\"\/wp-content\/themes\/watv\/images\/posts\/news_230704_08.jpg\" data-med-size=\"960x640\">\n   <img decoding=\"async\" src=\"\/wp-content\/themes\/watv\/images\/posts\/news_230704_08.jpg\" itemprop=\"thumbnail\" alt=\"Image description\" \/>\n  <\/a>\n <\/figure>\n<figure>\n  <a href=\"\/wp-content\/themes\/watv\/images\/posts\/news_230704_09@2x.jpg\" data-size=\"1400x924\" \n   data-med=\"\/wp-content\/themes\/watv\/images\/posts\/news_230704_09.jpg\" data-med-size=\"960x640\">\n   <img decoding=\"async\" src=\"\/wp-content\/themes\/watv\/images\/posts\/news_230704_09.jpg\" itemprop=\"thumbnail\" alt=\"Image description\" \/>\n  <\/a>\n <\/figure>\n<\/div>\n<figure class=\"full-width\">\n <picture class=\"copyright\"><source media=\"(max-width:450px)\" srcset=\"\/wp-content\/themes\/watv\/images\/posts\/news_230704_10.jpg\"><img decoding=\"async\" src=\"\/wp-content\/themes\/watv\/images\/posts\/news_230704_10.jpg\"\n    srcset=\"\/wp-content\/themes\/watv\/images\/posts\/news_230704_10.jpg,\n            \/wp-content\/themes\/watv\/images\/posts\/news_230704_10@2x.jpg 2x\">\n <\/picture>\n<\/figure>\n","protected":false},"excerpt":{"rendered":"Die Gemeinde Gottes, die sich f\u00fcr das Gl\u00fcck der Menschen und eine nachhaltige Umwelt einsetzt, und die peruanische Regierung, die eine nachhaltige Entwicklung der Gesellschaft und des Landes anstrebt, arbeiten solidarisch zusammen. Der peruanische Minister f\u00fcr Entwicklung und soziale Eingliederung, Julio Demartini, besuchte Korea, um am globalen Ministertreffen der Unterst\u00fctzungsl\u00e4nder zur Bewegung \u201eNeues Dorf\u201c 2023&#8230;","protected":false},"author":21,"featured_media":96742,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"post-type\/post-type-header-full-screen.php","format":"standard","meta":{"footnotes":""},"categories":[563,564],"tags":[],"class_list":["post-98757","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","category-global-news"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>ASEZ-Forum mit dem Minister f\u00fcr Entwicklung und soziale Eingliederung von Peru - GEMEINDE GOTTES DES WELTMISSIONSVEREINS<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/watv.org\/de\/asezwao-peru-forum-230704\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ASEZ-Forum mit dem Minister f\u00fcr Entwicklung und soziale Eingliederung von Peru - GEMEINDE GOTTES DES WELTMISSIONSVEREINS\" \/>\n<meta property=\"og:description\" content=\"Die Gemeinde Gottes, die sich f\u00fcr das Gl\u00fcck der Menschen und eine nachhaltige Umwelt einsetzt, und die peruanische Regierung, die eine nachhaltige Entwicklung der Gesellschaft und des Landes anstrebt, arbeiten solidarisch zusammen. Der peruanische Minister f\u00fcr Entwicklung und soziale Eingliederung, Julio Demartini, besuchte Korea, um am globalen Ministertreffen der Unterst\u00fctzungsl\u00e4nder zur Bewegung \u201eNeues Dorf\u201c 2023...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/watv.org\/de\/asezwao-peru-forum-230704\/\" \/>\n<meta property=\"og:site_name\" content=\"GEMEINDE GOTTES DES WELTMISSIONSVEREINS\" \/>\n<meta property=\"article:published_time\" content=\"2023-07-03T22:00:07+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-01-30T07:19:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/watv.org\/wp-content\/uploads\/2023\/08\/thum_asez_wao_peru_forum.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"3840\" \/>\n\t<meta property=\"og:image:height\" content=\"2000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ss\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/watv.org\\\/de\\\/asezwao-peru-forum-230704\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/watv.org\\\/de\\\/asezwao-peru-forum-230704\\\/\"},\"author\":{\"name\":\"ss\",\"@id\":\"https:\\\/\\\/watv.org\\\/de\\\/#\\\/schema\\\/person\\\/a58a271de4ef926ff9477cac3b74b5d5\"},\"headline\":\"ASEZ-Forum mit dem Minister f\u00fcr Entwicklung und soziale Eingliederung von Peru\",\"datePublished\":\"2023-07-03T22:00:07+00:00\",\"dateModified\":\"2024-01-30T07:19:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/watv.org\\\/de\\\/asezwao-peru-forum-230704\\\/\"},\"wordCount\":474,\"publisher\":{\"@id\":\"https:\\\/\\\/watv.org\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/watv.org\\\/de\\\/asezwao-peru-forum-230704\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/watv.org\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/thum_asez_wao_peru_forum.jpg\",\"articleSection\":[\"Welthauptsitz der WMC\",\"Globale Nachrichten\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/watv.org\\\/de\\\/asezwao-peru-forum-230704\\\/\",\"url\":\"https:\\\/\\\/watv.org\\\/de\\\/asezwao-peru-forum-230704\\\/\",\"name\":\"ASEZ-Forum mit dem Minister f\u00fcr Entwicklung und soziale Eingliederung von Peru - GEMEINDE GOTTES DES WELTMISSIONSVEREINS\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/watv.org\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/watv.org\\\/de\\\/asezwao-peru-forum-230704\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/watv.org\\\/de\\\/asezwao-peru-forum-230704\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/watv.org\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/thum_asez_wao_peru_forum.jpg\",\"datePublished\":\"2023-07-03T22:00:07+00:00\",\"dateModified\":\"2024-01-30T07:19:43+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/watv.org\\\/de\\\/asezwao-peru-forum-230704\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/watv.org\\\/de\\\/asezwao-peru-forum-230704\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/watv.org\\\/de\\\/asezwao-peru-forum-230704\\\/#primaryimage\",\"url\":\"https:\\\/\\\/watv.org\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/thum_asez_wao_peru_forum.jpg\",\"contentUrl\":\"https:\\\/\\\/watv.org\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/thum_asez_wao_peru_forum.jpg\",\"width\":3840,\"height\":2000},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/watv.org\\\/de\\\/asezwao-peru-forum-230704\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/watv.org\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ASEZ-Forum mit dem Minister f\u00fcr Entwicklung und soziale Eingliederung von Peru\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/watv.org\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/watv.org\\\/de\\\/\",\"name\":\"GEMEINDE GOTTES DES WELTMISSIONSVEREINS\",\"description\":\"With Mother\u2019s heartwarming love, we deliver eternal happiness to seven billion people in the world.\",\"publisher\":{\"@id\":\"https:\\\/\\\/watv.org\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/watv.org\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/watv.org\\\/de\\\/#organization\",\"name\":\"World Mission Society Church of God - \ud558\ub098\ub2d8\uc758\uad50\ud68c \uc138\uacc4\ubcf5\uc74c\uc120\uad50\ud611\ud68c\",\"url\":\"https:\\\/\\\/watv.org\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/watv.org\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/watv.org\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/WorldMissionSociety_ChurchofGod_Symbol_Logo.png\",\"contentUrl\":\"https:\\\/\\\/watv.org\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/WorldMissionSociety_ChurchofGod_Symbol_Logo.png\",\"width\":1001,\"height\":1331,\"caption\":\"World Mission Society Church of God - \ud558\ub098\ub2d8\uc758\uad50\ud68c \uc138\uacc4\ubcf5\uc74c\uc120\uad50\ud611\ud68c\"},\"image\":{\"@id\":\"https:\\\/\\\/watv.org\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCioiBk9rS5Dv5j66hUipsuQ\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/watv.org\\\/de\\\/#\\\/schema\\\/person\\\/a58a271de4ef926ff9477cac3b74b5d5\",\"name\":\"ss\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ASEZ-Forum mit dem Minister f\u00fcr Entwicklung und soziale Eingliederung von Peru - GEMEINDE GOTTES DES WELTMISSIONSVEREINS","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/watv.org\/de\/asezwao-peru-forum-230704\/","og_locale":"de_DE","og_type":"article","og_title":"ASEZ-Forum mit dem Minister f\u00fcr Entwicklung und soziale Eingliederung von Peru - GEMEINDE GOTTES DES WELTMISSIONSVEREINS","og_description":"Die Gemeinde Gottes, die sich f\u00fcr das Gl\u00fcck der Menschen und eine nachhaltige Umwelt einsetzt, und die peruanische Regierung, die eine nachhaltige Entwicklung der Gesellschaft und des Landes anstrebt, arbeiten solidarisch zusammen. Der peruanische Minister f\u00fcr Entwicklung und soziale Eingliederung, Julio Demartini, besuchte Korea, um am globalen Ministertreffen der Unterst\u00fctzungsl\u00e4nder zur Bewegung \u201eNeues Dorf\u201c 2023...","og_url":"https:\/\/watv.org\/de\/asezwao-peru-forum-230704\/","og_site_name":"GEMEINDE GOTTES DES WELTMISSIONSVEREINS","article_published_time":"2023-07-03T22:00:07+00:00","article_modified_time":"2024-01-30T07:19:43+00:00","og_image":[{"width":3840,"height":2000,"url":"https:\/\/watv.org\/wp-content\/uploads\/2023\/08\/thum_asez_wao_peru_forum.jpg","type":"image\/jpeg"}],"author":"ss","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/watv.org\/de\/asezwao-peru-forum-230704\/#article","isPartOf":{"@id":"https:\/\/watv.org\/de\/asezwao-peru-forum-230704\/"},"author":{"name":"ss","@id":"https:\/\/watv.org\/de\/#\/schema\/person\/a58a271de4ef926ff9477cac3b74b5d5"},"headline":"ASEZ-Forum mit dem Minister f\u00fcr Entwicklung und soziale Eingliederung von Peru","datePublished":"2023-07-03T22:00:07+00:00","dateModified":"2024-01-30T07:19:43+00:00","mainEntityOfPage":{"@id":"https:\/\/watv.org\/de\/asezwao-peru-forum-230704\/"},"wordCount":474,"publisher":{"@id":"https:\/\/watv.org\/de\/#organization"},"image":{"@id":"https:\/\/watv.org\/de\/asezwao-peru-forum-230704\/#primaryimage"},"thumbnailUrl":"https:\/\/watv.org\/wp-content\/uploads\/2023\/08\/thum_asez_wao_peru_forum.jpg","articleSection":["Welthauptsitz der WMC","Globale Nachrichten"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/watv.org\/de\/asezwao-peru-forum-230704\/","url":"https:\/\/watv.org\/de\/asezwao-peru-forum-230704\/","name":"ASEZ-Forum mit dem Minister f\u00fcr Entwicklung und soziale Eingliederung von Peru - GEMEINDE GOTTES DES WELTMISSIONSVEREINS","isPartOf":{"@id":"https:\/\/watv.org\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/watv.org\/de\/asezwao-peru-forum-230704\/#primaryimage"},"image":{"@id":"https:\/\/watv.org\/de\/asezwao-peru-forum-230704\/#primaryimage"},"thumbnailUrl":"https:\/\/watv.org\/wp-content\/uploads\/2023\/08\/thum_asez_wao_peru_forum.jpg","datePublished":"2023-07-03T22:00:07+00:00","dateModified":"2024-01-30T07:19:43+00:00","breadcrumb":{"@id":"https:\/\/watv.org\/de\/asezwao-peru-forum-230704\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/watv.org\/de\/asezwao-peru-forum-230704\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/watv.org\/de\/asezwao-peru-forum-230704\/#primaryimage","url":"https:\/\/watv.org\/wp-content\/uploads\/2023\/08\/thum_asez_wao_peru_forum.jpg","contentUrl":"https:\/\/watv.org\/wp-content\/uploads\/2023\/08\/thum_asez_wao_peru_forum.jpg","width":3840,"height":2000},{"@type":"BreadcrumbList","@id":"https:\/\/watv.org\/de\/asezwao-peru-forum-230704\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/watv.org\/de\/"},{"@type":"ListItem","position":2,"name":"ASEZ-Forum mit dem Minister f\u00fcr Entwicklung und soziale Eingliederung von Peru"}]},{"@type":"WebSite","@id":"https:\/\/watv.org\/de\/#website","url":"https:\/\/watv.org\/de\/","name":"GEMEINDE GOTTES DES WELTMISSIONSVEREINS","description":"With Mother\u2019s heartwarming love, we deliver eternal happiness to seven billion people in the world.","publisher":{"@id":"https:\/\/watv.org\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/watv.org\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/watv.org\/de\/#organization","name":"World Mission Society Church of God - \ud558\ub098\ub2d8\uc758\uad50\ud68c \uc138\uacc4\ubcf5\uc74c\uc120\uad50\ud611\ud68c","url":"https:\/\/watv.org\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/watv.org\/de\/#\/schema\/logo\/image\/","url":"https:\/\/watv.org\/wp-content\/uploads\/2022\/06\/WorldMissionSociety_ChurchofGod_Symbol_Logo.png","contentUrl":"https:\/\/watv.org\/wp-content\/uploads\/2022\/06\/WorldMissionSociety_ChurchofGod_Symbol_Logo.png","width":1001,"height":1331,"caption":"World Mission Society Church of God - \ud558\ub098\ub2d8\uc758\uad50\ud68c \uc138\uacc4\ubcf5\uc74c\uc120\uad50\ud611\ud68c"},"image":{"@id":"https:\/\/watv.org\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.youtube.com\/channel\/UCioiBk9rS5Dv5j66hUipsuQ"]},{"@type":"Person","@id":"https:\/\/watv.org\/de\/#\/schema\/person\/a58a271de4ef926ff9477cac3b74b5d5","name":"ss"}]}},"_links":{"self":[{"href":"https:\/\/watv.org\/de\/wp-json\/wp\/v2\/posts\/98757","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/watv.org\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/watv.org\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/watv.org\/de\/wp-json\/wp\/v2\/users\/21"}],"replies":[{"embeddable":true,"href":"https:\/\/watv.org\/de\/wp-json\/wp\/v2\/comments?post=98757"}],"version-history":[{"count":5,"href":"https:\/\/watv.org\/de\/wp-json\/wp\/v2\/posts\/98757\/revisions"}],"predecessor-version":[{"id":107189,"href":"https:\/\/watv.org\/de\/wp-json\/wp\/v2\/posts\/98757\/revisions\/107189"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/watv.org\/de\/wp-json\/wp\/v2\/media\/96742"}],"wp:attachment":[{"href":"https:\/\/watv.org\/de\/wp-json\/wp\/v2\/media?parent=98757"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/watv.org\/de\/wp-json\/wp\/v2\/categories?post=98757"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/watv.org\/de\/wp-json\/wp\/v2\/tags?post=98757"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}